


{"id":6888,"date":"2022-12-14T09:08:01","date_gmt":"2022-12-14T08:08:01","guid":{"rendered":"https:\/\/www.montallegro.it\/magazine\/paolo-massa-e-manuele-furnari-intervista-doppia\/"},"modified":"2022-12-14T09:08:01","modified_gmt":"2022-12-14T08:08:01","slug":"paolo-massa-e-manuele-furnari-intervista-doppia","status":"publish","type":"post","link":"https:\/\/www.montallegro.it\/magazine\/paolo-massa-e-manuele-furnari-intervista-doppia\/","title":{"rendered":"Paolo Massa e Manuele Furnari: intervista doppia"},"content":{"rendered":"<p><strong>Paolo Massa<\/strong> (<a href=\"http:\/\/dev1.dayone.network\/specialisti\/paolo-massa\/\" target=\"_blank\" rel=\"noopener\">leggi qui la scheda<\/a>) e <strong>Manuele Furnari<\/strong> (<a href=\"http:\/\/dev1.dayone.network\/specialisti\/manuele-furnari\/\" target=\"_blank\" rel=\"noopener\">leggi qui la scheda<\/a>), specialisti in <strong>Gastroenterologia<\/strong>, si confrontano per la rubrica \u201c<strong>Generazioni in sala<\/strong>\u201d sui temi pi\u00f9 significativi della propria professione, ma anche sul proprio vissuto privato e sulle motivazioni che li hanno spinti a diventare chirurghi, scegliendo in particolare questa specifica disciplina.<\/p>\n<p><strong>&#8211; Quale professione voleva fare da bambino?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abIl mio sogno \u00e8 sempre stato quello di fare il medico: non so esattamente per quale motivo, dal momento che ero letteralmente terrorizzato dal pediatra che periodicamente mia madre consultava. Tuttavia quel tono sempre tranquillizzante, il fascino del camice bianco e quegli strani apparecchi che usava per poter dire \u201cstai bene\u201d hanno sempre stimolato il mio interesse\u00bb.<\/p>\n<p><strong>Manuele Furnari<\/strong> \u00abSempre voluto fare il medico. L&#8217;alternativa era pi\u00f9 complessa: l&#8217;astronauta\u00bb.<\/p>\n<p><strong>&#8211; Quando si \u00e8 iscritto a Medicina aveva gi\u00e0 un progetto professionale?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abMi piacevano molto gli argomenti che affrontavo: ne ero allo stesso tempo interessato e gratificato. Ma ero ben lontano da immaginare un progetto professionale, almeno fino al terzo e quarto anno di Universit\u00e0, quando ho iniziato a frequentare un reparto ospedaliero\u00bb.<\/p>\n<p><strong>Manuele Furnari<\/strong> \u00abNon una professione in particolare, ma il progetto di raggiungere la massima professionalit\u00e0 possibile\u00bb.<\/p>\n<p><strong>&#8211; Come ha scelto la sua specializzazione e perch\u00e9? C&#8217;\u00e8 stato un suo maestro, oppure un episodio, che ha influito su questa scelta?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abAl quarto anno di Medicina ho avuto la fortuna di conoscere il prof. Dodero, mio maestro, primario gastroenterologo dell\u2019Ospedale Galliera di Genova. Ho iniziato da allora a frequentare il suo reparto, gestito da medici preparati e disponibili. \u00c8 l\u00ec che si \u00e8 svolta praticamente tutta la mia carriera di clinico e di endoscopista. Negli ultimi anni, dopo aver deciso di abbandonare la struttura pubblica, sto proseguendo la mia attivit\u00e0 con grande soddisfazione presso Villa Montallegro che mi fornisce mezzi tecnici necessari per proseguire e migliorare la mia attivit\u00e0. Il prof. Dodero, studioso instancabile, paziente con noi giovani e prodigo di consigli e di esempi, \u00e8 riuscito a costruire e plasmare una generazione di gastroenterologi e di endoscopisti. Lo ricordo con affetto e gratitudine: grande uomo\u00bb.<\/p>\n<p><strong>Manuele Furnari<\/strong> \u00abSono rimasto indeciso per lungo tempo, poich\u00e9 attratto dalla Medicina come tale. Dopo aver vagato tra diverse specialit\u00e0 chirurgiche mi sono avvicinato alla branca delle specialistiche internistiche, grazie al coinvolgimento e responsabilizzazione di un medico internista, per poi scegliere una specialit\u00e0 in grado di offrire aspetti sia internistici sia pratici, quale appunto la Gastroenterologia ed Endoscopia digestiva. Anche qui ha influito il colloquio con il mio primo mentore\u00bb.<\/p>\n<p><strong>&#8211; Cosa pensa di aver insegnato e imparato in questi anni di professione?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abHo imparato moltissimo e tutt\u2019ora continuo a imparare. La medicina negli anni \u00e8 cambiata moltissimo; si \u00e8 verificata una vera rivoluzione tecnologica. Basti pensare ai progressi dell\u2019imaging radiologico (ecografia, TC, RM, PET, etc), alle nuove tecnologie applicate all\u2019endoscopia che ci consentono l\u2019esplorazione di nuovi \u201cmondi\u201d, valutando organi che fino a qualche anno fa erano poco esplorabili; per non parlare della possibilit\u00e0 di acquisire i continui aggiornamenti professionali che arricchiscono in continuazione le nostre conoscenze. Occorre farne tesoro e confrontarsi con i colleghi, poich\u00e9 nel nostro lavoro \u00e8 fondamentale apprendere, ma utile insegnare: il \u201cdo ut des\u201d dei Latini\u00bb.<\/p>\n<p><strong>&#8211; Cosa trova di positivo nel confrontarsi con colleghi, in particolare se pi\u00f9 giovani?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abCon i colleghi pi\u00f9 giovani cerco di riprodurre, con i miei limiti, quanto ho imparato con l\u2019esempio dai miei colleghi pi\u00f9 anziani. Nel rispetto reciproco, la miscela di esperienza, con l\u2019aggiornamento professionale, la freschezza delle idee, l\u2019indubbia capacit\u00e0 di acquisire le novit\u00e0 tecnologiche sono i veri punti di forza del nostro lavoro. Userei due parole chiave: studio e confronto\u00bb.<\/p>\n<p><strong>&#8211; Cosa caratterizzava la sua specialit\u00e0 (diagnostica per immagini per inquadramento patologia, tecnologia chirurgica) quando ha iniziato?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abAll\u2019inizio della mia carriera erano fondamentali lo studio, l\u2019osservazione e l\u2019ascolto sia con i colleghi sia con i pazienti: sono i rudimenti per iniziare. Poi \u00e8 arrivata l\u2018attivit\u00e0 clinica che ben presto si \u00e8 completata con la mia pi\u00f9 grande passione che \u00e8 l\u2019endoscopia digestiva. Ripensare ai miei 40 anni di attivit\u00e0, mi porta a ricordare per esempio che, agli inizi, la semplice indagine ecografia era agli albori, che l&#8217;endoscopia veniva eseguita addirittura con strumenti semirigidi e che le nostre indagini erano solo esplorative, poich\u00e9 le possibilit\u00e0 tecnologiche consentivano un minimo di operativit\u00e0 solo nei centri pionieristici pi\u00f9 all\u2019avanguardia\u00bb.<\/p>\n<p><strong>&#8211; Quali sono le persone che Le hanno dato di pi\u00f9 in termini di esperienza trasmessa?<\/strong><\/p>\n<p><strong>Manuele Furnari<\/strong> \u00abCi sono state diverse persone che hanno influito per aspetti differenti. Chi da un punto di vista umano nel relazionarsi ai pazienti, chi da un punto di vista scientifico di ricerca e chi infine da un punto di vista tecnico. Per quest&#8217;ultimo aspetto ho diversi nomi in mente, uno per ogni Paese in cui ho lavorato o sono stato accolto per perfezionare la tecnica endoscopica\u00bb.<\/p>\n<p><strong>&#8211; Ricorda un caso che ha segnato la sua attivit\u00e0?<\/strong><\/p>\n<p><strong>Paolo Massa<\/strong> \u00abMio padre: un uomo eccezionale che ha sempre creduto in me, mi ha sempre incoraggiato e amato. Il destino ha voluto che si ammalasse di una patologia gastroenterologica e che si affidasse completamente a me. La commistione di due ruoli, quello di figlio e quello di gastroenterologo, ha rappresentato per me una prova veramente dura da affrontare. Certo che \u00e8 sempre esistita in noi medici una certa partecipazione emotiva alle vicende di salute che dobbiamo affrontare per i nostri pazienti, ma la sofferenza che ho provato credo abbia ulteriormente contribuito a una mia ulteriore umanizzazione nell\u2019approccio della sofferenza del singolo e degli affetti che lo circondano\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paolo Massa (leggi qui la scheda) e Manuele Furnari (leggi qui la scheda), specialisti in Gastroenterologia, si confrontano per la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1120,139],"tags":[371,977,976],"acf":[],"_links":{"self":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts\/6888"}],"collection":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/comments?post=6888"}],"version-history":[{"count":0,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts\/6888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/media\/6889"}],"wp:attachment":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/media?parent=6888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/categories?post=6888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/tags?post=6888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}