


{"id":6442,"date":"2021-10-19T17:24:57","date_gmt":"2021-10-19T15:24:57","guid":{"rendered":"https:\/\/www.montallegro.it\/magazine\/?p=6442"},"modified":"2022-02-04T18:10:21","modified_gmt":"2022-02-04T17:10:21","slug":"lanestesista-e-il-capitano-di-una-squadra-ma-gioca-in-difesa","status":"publish","type":"post","link":"https:\/\/www.montallegro.it\/magazine\/lanestesista-e-il-capitano-di-una-squadra-ma-gioca-in-difesa\/","title":{"rendered":"\u00abL&#8217;anestesista \u00e8 il capitano di una squadra ma gioca in difesa\u00bb"},"content":{"rendered":"<p align=\"JUSTIFY\"><b><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-6439 alignleft\" src=\"https:\/\/www.montallegro.it\/magazine\/wp-content\/uploads\/sites\/2\/2021\/10\/giovanni-mancuso-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.montallegro.it\/magazine\/wp-content\/uploads\/sites\/2\/2021\/10\/giovanni-mancuso-200x300.jpg 200w, https:\/\/www.montallegro.it\/magazine\/wp-content\/uploads\/sites\/2\/2021\/10\/giovanni-mancuso.jpg 682w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>&#8211; Perch\u00e9 ha scelto la specializzazione in anestesia e rianimazione che, tra l&#8217;altro, comporta un lavoro in un ospedale con limiti per la libera professione?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>Perch\u00e9 \u00e8 una specialit\u00e0 che ti richiede doti sia manuali sia tecniche; per la quale devi avere una conoscenza a 360 gradi della medicina e di tutti i processi fisiopatologici<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; L&#8217;anestesista \u00e8 paragonabile a un mediano che \u201ctiene assieme\u201d la squadra permettendo al chirurgo-bomber di andare in rete? O anche l&#8217;anestesista spesso diventa bomber?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span><span style=\"font-family: Times New Roman, serif\">\u00c8<\/span> pi\u00f9 il capitano della squadra, che avendo la visione d\u2019insieme pu\u00f2 impostare la strategia di gioco complessiva. Ma gioca in difesa, cercando di prevenire e in taluni casi deviare \u201ctiri pericolosi\u201d<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; Quale \u00e8 l&#8217;elemento fondamentale nel rapporto tra anestesista a paziente?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>Comprendere le paure del paziente, siano esse di carattere pratico o emotivo. E mostrare comprensione mantenendo una comunicazione chiara in modo da instaurare un rapporto di fiducia reciproca. In sostanza: trattare come vorremmo essere trattati<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; Ogni anestesista tende a specializzarsi su tecniche particolari. Per esempio le moderne tecniche che consentono la gestione del dolore dopo un intervento chirugico. Lei quali predilige e perch\u00e9?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>Premesso che tutte le tecniche sono valide se se ne ha conoscenza ed esperienza, il solo fatto di riuscire a ridurre l\u2019impatto fisico ed emotivo dovuto al dolore postoperatorio \u00e8 per noi fonte di grande soddisfazione. Personalmente prediligo le tecniche di blocco di parete (tap block) per rapidit\u00e0 di azione e di esecuzione, precisione e per profilo di sicurezza (bilancio a favore del beneficio rispetto al rischio). Se poi associamo questa tecnica all\u2019ausilio di farmaci endovenosi anche di bassa potenza (ovviamente a bassissimo dosaggio azzerandone cos\u00ec gli effetti collaterali) il successo \u00e8 assicurato<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; Un aneddoto che riassuma la sua esperienza professionale.<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>Impossibile riassumere: ogni intervento, ogni paziente, ogni chirurgo, ogni situazione \u00e8 differente nelle sue peculiarit\u00e0. Ma questo mestiere mi ha insegnato che molto frequentemente ci\u00f2 che appare non \u00e8 ci\u00f2 che \u00e8 nella realt\u00e0, e che si trova una soluzione per quasi ogni problema<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; Alcuni pazienti temono di \u201csvegliarsi\u201d durante l&#8217;intervento chirurgico: \u00e8 possibile? Come si evita questo rischio?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>C\u2019\u00e8 un\u2019ampia bibliografia sull\u2019argomento ed \u00e8 pertanto possibile che ci\u00f2 avvenga. Tuttavia oggi, con la misurazione dell\u2019EEG intraoperatorio che nella nostra struttura si esegue di routine, questa possibilit\u00e0 \u00e8 ridotta al minimo, per non dire \u00e8 impossibile<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; Lei ha un passato in strutture pubbliche, ma ha scelto di entrare in una casa di cura privata. Quale \u00e8 il progetto che l&#8217;ha convinta a fare questo passo?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>Il lavoro in una struttura privata risulta pi\u00f9 gratificante dal momento che, pur mantenendoti aderente ai protocolli di sicurezza, ti permette di avere pi\u00f9 tempo per il paziente e di operare pertanto delle scelte tagliate \u201csu misura\u201d sul paziente stesso. Riassumendo: risultato e customer satisfaction<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><b>&#8211; A Montallegro il gruppo di anestesisti \u00e8 considerato un elemento di qualit\u00e0 e di riconoscibilit\u00e0. Lei come vive questa esperienza?<\/b><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\">\u00ab<\/span>Il solo far parte di un gruppo di professionisti cos\u00ec validi sia dal punto di vista della conoscenza che dell\u2019esperienza sul campo, da un lato mi gratifica e dall\u2019altro mi fa sentire \u201cal sicuro\u201d; garantisco che la seconda sensazione \u00e8 la pi\u00f9 importante<span style=\"font-family: Times New Roman, serif\">\u00bb<\/span>.<\/p>\n<p align=\"JUSTIFY\"><em>La <\/em><a href=\"https:\/\/www.montallegro.it\/specialisti\/giovanni-mancuso\/\"><em>scheda<\/em><\/a><em> di <\/em><em>Giovanni Mancuso<\/em><em>.<\/em><\/p>\n<p align=\"JUSTIFY\"><em><a href=\"https:\/\/youtu.be\/j3Kg5kBFfIU\">Qui<\/a> il filmato dell&#8217;intervista doppia Giovanni Mancuso-David Razzoli.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Perch\u00e9 ha scelto la specializzazione in anestesia e rianimazione che, tra l&#8217;altro, comporta un lavoro in un ospedale con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[139,1107],"tags":[587,1043,592,36],"acf":[],"_links":{"self":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts\/6442"}],"collection":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/comments?post=6442"}],"version-history":[{"count":12,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts\/6442\/revisions"}],"predecessor-version":[{"id":6458,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/posts\/6442\/revisions\/6458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/media\/6438"}],"wp:attachment":[{"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/media?parent=6442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/categories?post=6442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.montallegro.it\/magazine\/wp-json\/wp\/v2\/tags?post=6442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}